{"id":10799,"date":"2026-02-02T04:05:00","date_gmt":"2026-02-02T03:05:00","guid":{"rendered":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/?post_type=einsatz&#038;p=10799"},"modified":"2026-02-02T11:14:22","modified_gmt":"2026-02-02T10:14:22","slug":"hy-tuer-notfalltueroeffnung-3","status":"publish","type":"einsatz","link":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/","title":{"rendered":"HY T\u00dcR &#8211; Notfallt\u00fcr\u00f6ffnung"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Am sehr fr\u00fchen Montagmorgen mussten wir unter Dringlichkeit eine Wohnungst\u00fcre \u00f6ffnen und Zugang f\u00fcr den Rettungsdienst schaffen.<\/p>\n","protected":false},"author":6,"featured_media":8827,"template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","einsatz_weight":1,"footnotes":""},"categories":[59],"tags":[109,69],"einsatzart":[11],"fahrzeug":[21,35],"exteinsatzmittel":[43,44],"alarmierungsart":[12],"evw_unit":[190],"class_list":["post-10799","einsatz","type-einsatz","status-publish","has-post-thumbnail","hentry","category-einsatz","tag-notfalltueroeffnung","tag-technische-hilfe","einsatzart-thl","fahrzeug-elw","fahrzeug-lf1612_cafs","exteinsatzmittel-drk-rd","exteinsatzmittel-polizei","alarmierungsart-funkmelder","evw_unit-ff-markdorf-schleife-tueroeffnung","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HY T\u00dcR - Notfallt\u00fcr\u00f6ffnung<\/title>\n<meta name=\"description\" content=\"Am sehr fr\u00fchen Montagmorgen mussten wir unter Dringlichkeit eine Wohnungst\u00fcre \u00f6ffnen und Zugang f\u00fcr den Rettungsdienst schaffen.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HY T\u00dcR - Notfallt\u00fcr\u00f6ffnung\" \/>\n<meta property=\"og:description\" content=\"Am sehr fr\u00fchen Montagmorgen mussten wir unter Dringlichkeit eine Wohnungst\u00fcre \u00f6ffnen und Zugang f\u00fcr den Rettungsdienst schaffen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Freiwillige Feuerwehr Markdorf\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/feuerwehrmarkdorf\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T10:14:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2024\/07\/Symbolbild-13a-Tueroeffnung-dringend.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"Report\"],\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/\"},\"author\":{\"name\":\"mscheerer\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#\\\/schema\\\/person\\\/332479352d6e81750d9ab7ac3745262c\"},\"headline\":\"HY T\u00dcR &#8211; Notfallt\u00fcr\u00f6ffnung\",\"datePublished\":\"2026-02-02T03:05:00+00:00\",\"dateModified\":\"2026-02-02T10:14:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/\"},\"wordCount\":27,\"publisher\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Symbolbild-13a-Tueroeffnung-dringend.jpg\",\"keywords\":[\"notfallt\u00fcr\u00f6ffnung\",\"Technische Hilfe\"],\"articleSection\":[\"Einsatz\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/\",\"url\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/\",\"name\":\"HY T\u00dcR - Notfallt\u00fcr\u00f6ffnung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Symbolbild-13a-Tueroeffnung-dringend.jpg\",\"datePublished\":\"2026-02-02T03:05:00+00:00\",\"dateModified\":\"2026-02-02T10:14:22+00:00\",\"description\":\"Am sehr fr\u00fchen Montagmorgen mussten wir unter Dringlichkeit eine Wohnungst\u00fcre \u00f6ffnen und Zugang f\u00fcr den Rettungsdienst schaffen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Symbolbild-13a-Tueroeffnung-dringend.jpg\",\"contentUrl\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/Symbolbild-13a-Tueroeffnung-dringend.jpg\",\"width\":992,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/hy-tuer-notfalltueroeffnung-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einsatzberichte\",\"item\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/einsaetze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HY T\u00dcR &#8211; Notfallt\u00fcr\u00f6ffnung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#website\",\"url\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/\",\"name\":\"Freiwillige Feuerwehr Markdorf\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#organization\",\"name\":\"Freiwillige Feuerwehr Markdorf\",\"url\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/FFM-red-ohne-Abteilung_klein.png\",\"contentUrl\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/FFM-red-ohne-Abteilung_klein.png\",\"width\":397,\"height\":170,\"caption\":\"Freiwillige Feuerwehr Markdorf\"},\"image\":{\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/feuerwehrmarkdorf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/#\\\/schema\\\/person\\\/332479352d6e81750d9ab7ac3745262c\",\"name\":\"mscheerer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c05798694e4a2d8a49e8c991a61e829ed7435b3699df1a726e5dbcd1f8e972b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c05798694e4a2d8a49e8c991a61e829ed7435b3699df1a726e5dbcd1f8e972b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c05798694e4a2d8a49e8c991a61e829ed7435b3699df1a726e5dbcd1f8e972b0?s=96&d=mm&r=g\",\"caption\":\"mscheerer\"},\"url\":\"https:\\\/\\\/feuerwehr-markdorf.de\\\/feuerwehr\\\/author\\\/mscheerer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HY T\u00dcR - Notfallt\u00fcr\u00f6ffnung","description":"Am sehr fr\u00fchen Montagmorgen mussten wir unter Dringlichkeit eine Wohnungst\u00fcre \u00f6ffnen und Zugang f\u00fcr den Rettungsdienst schaffen.","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"HY T\u00dcR - Notfallt\u00fcr\u00f6ffnung","og_description":"Am sehr fr\u00fchen Montagmorgen mussten wir unter Dringlichkeit eine Wohnungst\u00fcre \u00f6ffnen und Zugang f\u00fcr den Rettungsdienst schaffen.","og_url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/","og_site_name":"Freiwillige Feuerwehr Markdorf","article_publisher":"https:\/\/www.facebook.com\/feuerwehrmarkdorf\/","article_modified_time":"2026-02-02T10:14:22+00:00","og_image":[{"width":992,"height":709,"url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2024\/07\/Symbolbild-13a-Tueroeffnung-dringend.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","Report"],"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/#article","isPartOf":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/"},"author":{"name":"mscheerer","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#\/schema\/person\/332479352d6e81750d9ab7ac3745262c"},"headline":"HY T\u00dcR &#8211; Notfallt\u00fcr\u00f6ffnung","datePublished":"2026-02-02T03:05:00+00:00","dateModified":"2026-02-02T10:14:22+00:00","mainEntityOfPage":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/"},"wordCount":27,"publisher":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#organization"},"image":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/#primaryimage"},"thumbnailUrl":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2024\/07\/Symbolbild-13a-Tueroeffnung-dringend.jpg","keywords":["notfallt\u00fcr\u00f6ffnung","Technische Hilfe"],"articleSection":["Einsatz"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/","url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/","name":"HY T\u00dcR - Notfallt\u00fcr\u00f6ffnung","isPartOf":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/#primaryimage"},"image":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/#primaryimage"},"thumbnailUrl":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2024\/07\/Symbolbild-13a-Tueroeffnung-dringend.jpg","datePublished":"2026-02-02T03:05:00+00:00","dateModified":"2026-02-02T10:14:22+00:00","description":"Am sehr fr\u00fchen Montagmorgen mussten wir unter Dringlichkeit eine Wohnungst\u00fcre \u00f6ffnen und Zugang f\u00fcr den Rettungsdienst schaffen.","breadcrumb":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/#primaryimage","url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2024\/07\/Symbolbild-13a-Tueroeffnung-dringend.jpg","contentUrl":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2024\/07\/Symbolbild-13a-Tueroeffnung-dringend.jpg","width":992,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/hy-tuer-notfalltueroeffnung-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/"},{"@type":"ListItem","position":2,"name":"Einsatzberichte","item":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsaetze\/"},{"@type":"ListItem","position":3,"name":"HY T\u00dcR &#8211; Notfallt\u00fcr\u00f6ffnung"}]},{"@type":"WebSite","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#website","url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/","name":"Freiwillige Feuerwehr Markdorf","description":"","publisher":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#organization","name":"Freiwillige Feuerwehr Markdorf","url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#\/schema\/logo\/image\/","url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2020\/01\/FFM-red-ohne-Abteilung_klein.png","contentUrl":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2020\/01\/FFM-red-ohne-Abteilung_klein.png","width":397,"height":170,"caption":"Freiwillige Feuerwehr Markdorf"},"image":{"@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/feuerwehrmarkdorf\/"]},{"@type":"Person","@id":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/#\/schema\/person\/332479352d6e81750d9ab7ac3745262c","name":"mscheerer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c05798694e4a2d8a49e8c991a61e829ed7435b3699df1a726e5dbcd1f8e972b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c05798694e4a2d8a49e8c991a61e829ed7435b3699df1a726e5dbcd1f8e972b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c05798694e4a2d8a49e8c991a61e829ed7435b3699df1a726e5dbcd1f8e972b0?s=96&d=mm&r=g","caption":"mscheerer"},"url":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/author\/mscheerer\/"}]}},"featured_img":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-content\/uploads\/sites\/2\/2024\/07\/Symbolbild-13a-Tueroeffnung-dringend.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/author\/mscheerer\/","display_name":"mscheerer"},"relative_dates":{"created":"Posted 5\u00a0Monaten ago","modified":"Updated 5\u00a0Monaten ago"},"absolute_dates":{"created":"Posted on 2. Februar 2026","modified":"Updated on 2. Februar 2026"},"absolute_dates_time":{"created":"Posted on 2. Februar 2026 4:05","modified":"Updated on 2. Februar 2026 11:14"},"featured_img_caption":"","tax_additional":{"category":{"linked":["<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/category\/einsatz\/\" class=\"advgb-post-tax-term\">Einsatz<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Einsatz<\/span>"],"slug":"category","name":"Kategorien"},"post_tag":{"linked":["<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/tag\/notfalltueroeffnung\/\" class=\"advgb-post-tax-term\">notfallt\u00fcr\u00f6ffnung<\/a>","<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/tag\/technische-hilfe\/\" class=\"advgb-post-tax-term\">Technische Hilfe<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">notfallt\u00fcr\u00f6ffnung<\/span>","<span class=\"advgb-post-tax-term\">Technische Hilfe<\/span>"],"slug":"post_tag","name":"Schlagw\u00f6rter"},"einsatzart":{"linked":["<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/einsatzart\/thl\/\" class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/span>"],"slug":"einsatzart","name":"Einsatzarten"},"fahrzeug":{"linked":["<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/fahrzeug\/elw\/\" class=\"advgb-post-tax-term\">ELW<\/a>","<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/fahrzeug\/lf1612_cafs\/\" class=\"advgb-post-tax-term\">LF 16\/12 CAFS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ELW<\/span>","<span class=\"advgb-post-tax-term\">LF 16\/12 CAFS<\/span>"],"slug":"fahrzeug","name":"Fahrzeuge"},"exteinsatzmittel":{"linked":["<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/externe-einsatzmittel\/drk-rd\/\" class=\"advgb-post-tax-term\">DRK Rettungsdienst<\/a>","<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/externe-einsatzmittel\/polizei\/\" class=\"advgb-post-tax-term\">Polizei<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">DRK Rettungsdienst<\/span>","<span class=\"advgb-post-tax-term\">Polizei<\/span>"],"slug":"exteinsatzmittel","name":"Externe Einsatzmittel"},"alarmierungsart":{"linked":["<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/alarmierungsart\/funkmelder\/\" class=\"advgb-post-tax-term\">Funkmeldeempf\u00e4nger<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Funkmeldeempf\u00e4nger<\/span>"],"slug":"alarmierungsart","name":"Alarmierungsarten"},"evw_unit":{"linked":["<a href=\"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/evw_unit\/ff-markdorf-schleife-tueroeffnung\/\" class=\"advgb-post-tax-term\">FF Markdorf - Schleife &quot;T\u00fcr\u00f6ffnung&quot;<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FF Markdorf - Schleife &quot;T\u00fcr\u00f6ffnung&quot;<\/span>"],"slug":"evw_unit","name":"Einheiten"}},"series_order":"","_links":{"self":[{"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/einsatz\/10799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/einsatz"}],"about":[{"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/types\/einsatz"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":1,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/einsatz\/10799\/revisions"}],"predecessor-version":[{"id":10800,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/einsatz\/10799\/revisions\/10800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/media\/8827"}],"wp:attachment":[{"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/media?parent=10799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/categories?post=10799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/tags?post=10799"},{"taxonomy":"einsatzart","embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/einsatzart?post=10799"},{"taxonomy":"fahrzeug","embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/fahrzeug?post=10799"},{"taxonomy":"exteinsatzmittel","embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/exteinsatzmittel?post=10799"},{"taxonomy":"alarmierungsart","embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/alarmierungsart?post=10799"},{"taxonomy":"evw_unit","embeddable":true,"href":"https:\/\/feuerwehr-markdorf.de\/feuerwehr\/wp-json\/wp\/v2\/evw_unit?post=10799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}